{"id":9217,"date":"2025-11-22T14:50:16","date_gmt":"2025-11-22T14:50:16","guid":{"rendered":"https:\/\/natation.ch\/product\/bolster-paddles\/"},"modified":"2026-01-04T20:28:18","modified_gmt":"2026-01-04T20:28:18","slug":"bolster-paddles","status":"publish","type":"product","link":"https:\/\/natation.ch\/it\/prodotto\/bolster-paddles\/","title":{"rendered":"Bolster Paddles"},"content":{"rendered":"<div class=\"col-sm-6 fab-left-column\">\n<div class=\"fab-left\">\n<div class=\"col-sm-12\">\n<ul>\n<li>Promuove una posizione verticale anticipata dell&#8217;avambraccio (EVF) e aumenta l&#8217;efficienza della bracciata<\/li>\n<li>Crea e mantiene una velocit\u00e0 di picco pi\u00f9 lunga durante la fase di potenza della bracciata<\/li>\n<li>La cinghia in velcro facilmente regolabile mantiene comodamente il polso in posizione<\/li>\n<li>Richiede una presa alta sollevando il gomito, ideale per l&#8217;allenamento in acque libere e triathlon<\/li>\n<li>Strumento versatile per farfalla, dorso, rana e stile libero<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le palette Bolster sviluppano una posizione verticale anticipata dell&#8217;avambraccio (EVF) e aumentano l&#8217;efficienza della bracciata. Una posizione EVF utilizza l&#8217;intero avambraccio durante la trazione, creando un&#8217;applicazione uniforme della forza dalla punta delle dita al gomito. Questo crea e mantiene una velocit\u00e0 di picco pi\u00f9 lunga durante la fase di potenza della bracciata. Allo stesso tempo, crea percorsi neurali per la forza specifica della bracciata. Il perfezionamento corretto della bracciata \u00e8 promosso attraverso la memoria muscolare della corretta posizione di mano, polso e avambraccio. Le palette Bolster sono uno strumento versatile per tutti e quattro gli stili di nuoto.<\/p>\n<p>Finis<\/p>\n","protected":false},"featured_media":410,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[327],"product_cat":[74,85],"product_tag":[],"class_list":{"0":"post-9217","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-finis","7":"product_cat-attrezzatura","8":"product_cat-paddle","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/natation.ch\/it\/wp-json\/wp\/v2\/product\/9217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natation.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/natation.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/natation.ch\/it\/wp-json\/wp\/v2\/comments?post=9217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/natation.ch\/it\/wp-json\/wp\/v2\/media\/410"}],"wp:attachment":[{"href":"https:\/\/natation.ch\/it\/wp-json\/wp\/v2\/media?parent=9217"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/natation.ch\/it\/wp-json\/wp\/v2\/product_brand?post=9217"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/natation.ch\/it\/wp-json\/wp\/v2\/product_cat?post=9217"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/natation.ch\/it\/wp-json\/wp\/v2\/product_tag?post=9217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}